{"id":141,"date":"2008-01-17T00:03:28","date_gmt":"2008-01-16T22:03:28","guid":{"rendered":"http:\/\/formschub.de\/blog\/?p=141"},"modified":"2020-06-30T22:10:18","modified_gmt":"2020-06-30T20:10:18","slug":"porree-fisch-rouladen-in-zitronen-senf-sauce","status":"publish","type":"post","link":"https:\/\/www.formschub.de\/blog\/2008\/01\/17\/porree-fisch-rouladen-in-zitronen-senf-sauce\/","title":{"rendered":"Porree-Fisch-Rouladen in Zitronen-Senf-Sauce"},"content":{"rendered":"<p><strong>Zutaten<\/strong><em><br \/>\nf\u00fcr 2 Personen<\/em><\/p>\n<p>ca. 400 g Seeteufelb\u00e4ckchen (klingt teurer, als es ist!)<br \/>\n2 m\u00f6glichst dicke Stangen Porree<br \/>\n1 kleine unbehandelte Zitrone<br \/>\n1 kleine Zwiebel<br \/>\nMadeira<br \/>\n3 EL Creme fraiche<br \/>\n100 ml Sahne<br \/>\n2 TL Dijon-Senf mit Honig<br \/>\nOliven\u00f6l, Zitronenpfeffer, Meersalz<br \/>\nH\u00f6lzerne Zahnstocher<\/p>\n<p>Die Seeteufelb\u00e4ckchen absp\u00fclen, trockentupfen, von der z\u00e4hen Haut befreien und mit Zitronenpfeffer und Meersalz leicht w\u00fcrzen.<\/p>\n<p>Die Zitronenschale d\u00fcnn absch\u00e4len und den Saft der Zitrone auspressen.<\/p>\n<p>Welke \u00e4u\u00dfere Bl\u00e4tter der Porreestangen abl\u00f6sen, Wurzelende und gr\u00fcne Blattbereiche abschneiden und die Stangen l\u00e4ngs bis zum Kern einschneiden und die so entstehenden langen Porreeblatt-Rechtecke absch\u00e4len und in eine flache Sch\u00fcssel (z.B. Auflaufform) legen. Die Bl\u00e4tter mit kochendem Wasser \u00fcbergie\u00dfen, ca. 1 Minute blanchieren, kalt abschrecken, herausnehmen und trockentupfen.<\/p>\n<p>Nun jedes Seeteufelb\u00e4ckchen in ein Porreeblatt einrollen (zu lange Bl\u00e4tter ggf. k\u00fcrzen) und mit einem Zahnstocher feststecken. Die R\u00f6llchen in einer Pfanne in Oliven\u00f6l kr\u00e4ftig anbraten, so dass der Porree sch\u00f6n br\u00e4unt. R\u00f6llchen aus der Pfanne nehmen und auf einem abgedeckten Teller bei ca. 100 \u00b0C im Ofen warmstellen.<\/p>\n<p>In der Fischpfanne die Zwiebel glasig anbraten und mit einem Schuss Madeira und dem Zitronensaft abl\u00f6schen. Sahne, Creme fraiche und Senf einr\u00fchren, die Zitronenschale hineingeben und die Sauce auf kleiner Flamme ca. 10\u201315 min. einkochen lassen. Zitronenschale herausnehmen, die Sauce p\u00fcrieren und die Fischr\u00f6llchen samt ausgetretenem Sud aus dem Ofen zur\u00fcck mit der Sauce in die Pfanne geben.<\/p>\n<p>Dazu passen z.B. Zuckerschoten, gr\u00fcne Bohnen, Broccoli oder gr\u00fcner Spargel.<\/p>\n<p><img decoding=\"async\" src=\"http:\/\/formschub.de\/blog\/wp-content\/uploads\/2008\/01\/fischrouladen.jpg\" alt=\"fischrouladen.jpg\" \/><\/p>\n<p><em><span style=\"font-size: 12pt;\">\u00a9 Rezept und Foto: formschub<\/span><\/em><\/p>\n<div class=\"likebtn_container\" style=\"clear:both;\"><!-- LikeBtn.com BEGIN --><span class=\"likebtn-wrapper\"  data-identifier=\"post_141\"  data-site_id=\"5ec2910b6fd08bbb5dd94e1f\"  data-theme=\"heartcross\"  data-lang=\"de\"  data-show_dislike_label=\"true\"  data-share_enabled=\"false\"  data-counter_frmt=\"period\"  data-tooltip_enabled=\"false\"  data-i18n_like=\"gern gelesen\"  data-i18n_dislike=\"gefiel mir nicht\"  data-i18n_after_like=\"gern gelesen\"  data-i18n_after_dislike=\"gefiel mir nicht\"  data-i18n_like_tooltip=\"gern gelesen\"  data-i18n_dislike_tooltip=\"gefiel mir nicht\"  data-i18n_unlike_tooltip=\"\u2764\ufe0f entfernen\"  data-i18n_undislike_tooltip=\"\u274c entfernen\"  data-i18n_popup_close=\"schlie\u00dfen\"  data-i18n_popup_text=\"Danke f\u00fcr Deine Bewertung!\"  data-style=\"\"  data-unlike_allowed=\"\"  data-show_copyright=\"\"  data-item_url=\"https:\/\/www.formschub.de\/blog\/2008\/01\/17\/porree-fisch-rouladen-in-zitronen-senf-sauce\/\"  data-item_title=\"Porree-Fisch-Rouladen in Zitronen-Senf-Sauce\"  data-item_date=\"2008-01-17T00:03:28+01:00\"  data-engine=\"WordPress\"  data-plugin_v=\"2.6.59\"  data-prx=\"https:\/\/www.formschub.de\/blog\/wp-admin\/admin-ajax.php?action=likebtn_prx\"  data-event_handler=\"likebtn_eh\" ><\/span><!-- LikeBtn.com END --><\/div>","protected":false},"excerpt":{"rendered":"<p>Zutaten f\u00fcr 2 Personen ca. 400 g Seeteufelb\u00e4ckchen (klingt teurer, als es ist!) 2 m\u00f6glichst dicke Stangen Porree 1 kleine unbehandelte Zitrone 1 kleine Zwiebel [&#8230;]<\/p>\n<div class=\"likebtn_container\" style=\"clear:both;\"><!-- LikeBtn.com BEGIN --><span class=\"likebtn-wrapper\"  data-identifier=\"post_141\"  data-site_id=\"5ec2910b6fd08bbb5dd94e1f\"  data-theme=\"heartcross\"  data-lang=\"de\"  data-show_dislike_label=\"true\"  data-share_enabled=\"false\"  data-counter_frmt=\"period\"  data-tooltip_enabled=\"false\"  data-i18n_like=\"gern gelesen\"  data-i18n_dislike=\"gefiel mir nicht\"  data-i18n_after_like=\"gern gelesen\"  data-i18n_after_dislike=\"gefiel mir nicht\"  data-i18n_like_tooltip=\"gern gelesen\"  data-i18n_dislike_tooltip=\"gefiel mir nicht\"  data-i18n_unlike_tooltip=\"\u2764\ufe0f entfernen\"  data-i18n_undislike_tooltip=\"\u274c entfernen\"  data-i18n_popup_close=\"schlie\u00dfen\"  data-i18n_popup_text=\"Danke f\u00fcr Deine Bewertung!\"  data-style=\"\"  data-unlike_allowed=\"\"  data-show_copyright=\"\"  data-item_url=\"https:\/\/www.formschub.de\/blog\/2008\/01\/17\/porree-fisch-rouladen-in-zitronen-senf-sauce\/\"  data-item_title=\"Porree-Fisch-Rouladen in Zitronen-Senf-Sauce\"  data-item_date=\"2008-01-17T00:03:28+01:00\"  data-engine=\"WordPress\"  data-plugin_v=\"2.6.59\"  data-prx=\"https:\/\/www.formschub.de\/blog\/wp-admin\/admin-ajax.php?action=likebtn_prx\"  data-event_handler=\"likebtn_eh\" ><\/span><!-- LikeBtn.com END --><\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,1],"tags":[],"class_list":["post-141","post","type-post","status-publish","format-standard","hentry","category-aus-dem-kochbuch","category-von-der-tageskarte"],"_links":{"self":[{"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/posts\/141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/comments?post=141"}],"version-history":[{"count":3,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/posts\/141\/revisions"}],"predecessor-version":[{"id":5050,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/posts\/141\/revisions\/5050"}],"wp:attachment":[{"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/media?parent=141"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/categories?post=141"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/tags?post=141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}