{"id":8178,"date":"2023-08-06T20:57:39","date_gmt":"2023-08-06T18:57:39","guid":{"rendered":"https:\/\/www.formschub.de\/blog\/?p=8178"},"modified":"2023-08-07T11:42:50","modified_gmt":"2023-08-07T09:42:50","slug":"tafelrunde","status":"publish","type":"post","link":"https:\/\/www.formschub.de\/blog\/2023\/08\/06\/tafelrunde\/","title":{"rendered":"Tafelrunde"},"content":{"rendered":"\n<p>Seitdem ich blogge (etwa seit Ende 2006), poste ich hier auch Rezepte, meistens mit einem Foto der zubereiteten Speise. Und seitdem es Twitter, bzw. jetzt Mastodon gibt und ich dort Zeug poste (2008 bzw. Ende 2022), habe ich Kochergebnisse, Backresultate, Restaurantgedecke, Tellergerichte, Salatsch\u00fcsseln, Suppenterrinen mit allerlei selbst zubereiteten oder von externen Kochk\u00f6nnern servierten Speisen immer wieder gerne dokumentiert und erl\u00e4utert. Es macht mir Spa\u00df, meine Genusserlebnisse im Netz zu teilen, anderen Appetit zu machen, Interesse f\u00fcr kulinarisches Neuland oder interessante Rezepte zu wecken und nat\u00fcrlich auch, mich sp\u00e4ter selbst an wohlschmeckende Anl\u00e4sse wieder zu erinnern.<\/p>\n\n\n\n<p>Irgendwann begann ich, meine Foodfotos einfach immer ganz schlicht von oben zu fotografieren. Das hat auch \u00e4sthetische Gr\u00fcnde, aber haupts\u00e4chlich ist es ein recht effizienter \u00bbKniff\u00ab, Essen ansprechend, authentisch und unaufwendig abbilden zu k\u00f6nnen:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Man muss sich nicht um irgendwelche Hintergr\u00fcnde k\u00fcmmern, au\u00dfer dass die Tisch- oder Untergrundfl\u00e4che einigerma\u00dfen ansehnlich und aufger\u00e4umt sein sollte. In meiner K\u00fcche ist nicht viel Platz, ich nenne weder eine pittoreske Landhausk\u00fcche mein eigen, noch habe ich einen Garten, einen Innenhof, eine Veranda o.\u00e4., wo ich meine Fotos in einem passenden Ambiente anfertigen k\u00f6nnte.<\/li>\n\n\n\n<li>Durch den engen Bildausschnitt braucht man nur ein Minimum an Platz. Hauptsache, das Essen bzw. der relevante Teil des Serviergeschirrs ist im Bild. Es kommt der Entstehung von Fotos auch in Restaurants oft zugute, wenn man mit wenig Aufwand, geringem Aufsehen und ohne andere Personen mit im Sucher zu haben, fotografieren m\u00f6chte oder muss.<\/li>\n\n\n\n<li>Das Essen steht absolut im Fokus, nicht das Geschirr, nicht Besteck, Servietten, Trinkgef\u00e4\u00dfe oder andere Teile der Tischdekoration. Ich selbst besitze nur eine, wenn auch recht komplett ausgestattete Geschirrgarnitur in wei\u00df mit hellgr\u00fcner Rand-\/Au\u00dfenglasur. Und trotzdem kann ich damit auf diese Weise Fotos machen, die auf den ersten Blick alle v\u00f6llig unterschiedlich aussehen.<\/li>\n\n\n\n<li>Die Fotos bekommen eine Art \u00bbSeriencharakter\u00ab, obwohl sie an v\u00f6llig verschiedenen Orten, zu unterschiedlichen (Tages-)Zeiten und bei jedesmal anderer Beleuchtung aufgenommen wurden.<\/li>\n\n\n\n<li>Das quadratische Fotoformat mit dem inliegenden oder angedeuteten Kreis hat eine ganz eigene, sch\u00f6ne, stringente \u00c4sthetik und Symmetrie \u2013 quasi eine Art Wes-Anderson-Look, nur auf Foodfotos adaptiert.<\/li>\n\n\n\n<li>Diese Art der Aufnahme kann mit der Zeit auch eine Art \u00bbMarkenzeichen\u00ab werden, so dass Follower gleich erkennen, von wem das gerade neu gepostete Foodfoto wahrscheinlich wieder stammt.<\/li>\n<\/ul>\n\n\n\n<p>Als ich heute eine frisch gebackene Brombeerw\u00e4he in ihrer Springform fotografiert und gepostet hatte, fragte ich mich, wieviele Fotos ich wohl schon auf diese Art gemacht habe \u2013 und schaute mal interessehalber in meinem Archiv nach. Es waren \u00fcber 300. Eine Auswahl von 289 habe ich daraufhin einmal in einem 17 x 17 -Raster arrangiert und ich finde, das sieht auch als Mosaik sehr appetitanregend aus. <\/p>\n\n\n\n<p>Ich glaube, ich mache einfach genau so weiter. \ud83d\ude42<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.formschub.de\/blog\/wp-content\/uploads\/2023\/08\/289xEssen-scaled.jpg\" target=\"_blank\" rel=\"noreferrer noopener\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"2560\" src=\"https:\/\/www.formschub.de\/blog\/wp-content\/uploads\/2023\/08\/289xEssen-scaled.jpg\" alt=\"\" class=\"wp-image-8181\" srcset=\"https:\/\/www.formschub.de\/blog\/wp-content\/uploads\/2023\/08\/289xEssen-scaled.jpg 2560w, https:\/\/www.formschub.de\/blog\/wp-content\/uploads\/2023\/08\/289xEssen-300x300.jpg 300w, https:\/\/www.formschub.de\/blog\/wp-content\/uploads\/2023\/08\/289xEssen-1024x1024.jpg 1024w, https:\/\/www.formschub.de\/blog\/wp-content\/uploads\/2023\/08\/289xEssen-150x150.jpg 150w, https:\/\/www.formschub.de\/blog\/wp-content\/uploads\/2023\/08\/289xEssen-768x768.jpg 768w, https:\/\/www.formschub.de\/blog\/wp-content\/uploads\/2023\/08\/289xEssen-1536x1536.jpg 1536w, https:\/\/www.formschub.de\/blog\/wp-content\/uploads\/2023\/08\/289xEssen-2048x2048.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><figcaption class=\"wp-element-caption\">289 Leckereien. | <a rel=\"noreferrer noopener\" href=\"https:\/\/www.formschub.de\/blog\/wp-content\/uploads\/2023\/08\/289xEssen_XXL.jpg\" target=\"_blank\">Hier klicken<\/a> f\u00fcr XXL-Ansicht in neuem Tab (10 MB)<\/figcaption><\/figure>\n<div class=\"likebtn_container\" style=\"clear:both;\"><!-- LikeBtn.com BEGIN --><span class=\"likebtn-wrapper\"  data-identifier=\"post_8178\"  data-site_id=\"5ec2910b6fd08bbb5dd94e1f\"  data-theme=\"heartcross\"  data-lang=\"de\"  data-show_dislike_label=\"true\"  data-share_enabled=\"false\"  data-counter_frmt=\"period\"  data-tooltip_enabled=\"false\"  data-i18n_like=\"gern gelesen\"  data-i18n_dislike=\"gefiel mir nicht\"  data-i18n_after_like=\"gern gelesen\"  data-i18n_after_dislike=\"gefiel mir nicht\"  data-i18n_like_tooltip=\"gern gelesen\"  data-i18n_dislike_tooltip=\"gefiel mir nicht\"  data-i18n_unlike_tooltip=\"\u2764\ufe0f entfernen\"  data-i18n_undislike_tooltip=\"\u274c entfernen\"  data-i18n_popup_close=\"schlie\u00dfen\"  data-i18n_popup_text=\"Danke f\u00fcr Deine Bewertung!\"  data-style=\"\"  data-unlike_allowed=\"\"  data-show_copyright=\"\"  data-item_url=\"https:\/\/www.formschub.de\/blog\/2023\/08\/06\/tafelrunde\/\"  data-item_title=\"Tafelrunde\"  data-item_date=\"2023-08-06T20:57:39+02:00\"  data-engine=\"WordPress\"  data-plugin_v=\"2.6.59\"  data-prx=\"https:\/\/www.formschub.de\/blog\/wp-admin\/admin-ajax.php?action=likebtn_prx\"  data-event_handler=\"likebtn_eh\" ><\/span><!-- LikeBtn.com END --><\/div>","protected":false},"excerpt":{"rendered":"<p>Seitdem ich blogge (etwa seit Ende 2006), poste ich hier auch Rezepte, meistens mit einem Foto der zubereiteten Speise. Und seitdem es Twitter, bzw. jetzt [&#8230;]<\/p>\n<div class=\"likebtn_container\" style=\"clear:both;\"><!-- LikeBtn.com BEGIN --><span class=\"likebtn-wrapper\"  data-identifier=\"post_8178\"  data-site_id=\"5ec2910b6fd08bbb5dd94e1f\"  data-theme=\"heartcross\"  data-lang=\"de\"  data-show_dislike_label=\"true\"  data-share_enabled=\"false\"  data-counter_frmt=\"period\"  data-tooltip_enabled=\"false\"  data-i18n_like=\"gern gelesen\"  data-i18n_dislike=\"gefiel mir nicht\"  data-i18n_after_like=\"gern gelesen\"  data-i18n_after_dislike=\"gefiel mir nicht\"  data-i18n_like_tooltip=\"gern gelesen\"  data-i18n_dislike_tooltip=\"gefiel mir nicht\"  data-i18n_unlike_tooltip=\"\u2764\ufe0f entfernen\"  data-i18n_undislike_tooltip=\"\u274c entfernen\"  data-i18n_popup_close=\"schlie\u00dfen\"  data-i18n_popup_text=\"Danke f\u00fcr Deine Bewertung!\"  data-style=\"\"  data-unlike_allowed=\"\"  data-show_copyright=\"\"  data-item_url=\"https:\/\/www.formschub.de\/blog\/2023\/08\/06\/tafelrunde\/\"  data-item_title=\"Tafelrunde\"  data-item_date=\"2023-08-06T20:57:39+02:00\"  data-engine=\"WordPress\"  data-plugin_v=\"2.6.59\"  data-prx=\"https:\/\/www.formschub.de\/blog\/wp-admin\/admin-ajax.php?action=likebtn_prx\"  data-event_handler=\"likebtn_eh\" ><\/span><!-- LikeBtn.com END --><\/div>","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,1],"tags":[],"class_list":["post-8178","post","type-post","status-publish","format-standard","hentry","category-das-auge-isst-mit","category-von-der-tageskarte"],"_links":{"self":[{"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/posts\/8178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/comments?post=8178"}],"version-history":[{"count":18,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/posts\/8178\/revisions"}],"predecessor-version":[{"id":8202,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/posts\/8178\/revisions\/8202"}],"wp:attachment":[{"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/media?parent=8178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/categories?post=8178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.formschub.de\/blog\/wp-json\/wp\/v2\/tags?post=8178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}